{"id":12461,"date":"2006-07-06T00:00:00","date_gmt":"2006-07-06T05:00:00","guid":{"rendered":"https:\/\/encaso.volitivo.com\/site\/show1129\/"},"modified":"2006-07-06T00:00:00","modified_gmt":"2006-07-06T05:00:00","slug":"show1129","status":"publish","type":"post","link":"https:\/\/encaso.volitivo.com\/site\/show1129\/","title":{"rendered":"show1129"},"content":{"rendered":"<table width=\"550\" border=\"1\">\n<tr>\n<td align=\"center\">\n<h3>1129 SOMOS CERDOS &#8211; ECDQEMSD <\/h3>\n<\/td>\n<\/tr>\n<tr>\n<td align=\"center\">jueves&#44; 6 de julio de 2006<\/td>\n<\/tr>\n<tr>\n<td align=\"center\">En Caso de que el Mundo Se Desintegre &#8211; El Cyber Talk Show &#8211; Comunicaci\u00f3n entre hispanoparlantes<\/td>\n<\/tr>\n<tr>\n<td align=\"center\"> Descargar \/ Escuchar: <a href=\"https:\/\/encaso.volitivo.com\/programas\/1100\/ecdqemsd1129.wma\" target=\"_blank\"> encaso1129.wma<\/a><\/td>\n<\/tr>\n<tr>\n<td align=\"center\">Power by <a target=\"_blank\" href=\"http:\/\/www.canaltrans.com\/\"> CanalTrans.com<\/a> &copy; 2017\u00a0.:&#167;:. Streaming by<a href=\" \"> JPaulo<\/a><\/td>\n<\/tr>\n<tr>\n<td align=\"center\"><a href=\"show1128\"> &lt;&lt; == Anterior<\/a>  ==#&#167;#== <a href=\"show1130\">Siguiente ==&gt;&gt;<\/a><\/td>\n<\/tr>\n<\/table>\n","protected":false},"excerpt":{"rendered":"<p>1129 SOMOS CERDOS &#8211; ECDQEMSD jueves&#44; 6 de julio de 2006 En Caso de que el Mundo Se Desintegre &#8211;&hellip; <a class=\"read-more\" href=\"https:\/\/encaso.volitivo.com\/site\/show1129\/\">Read more <span class=\"screen-reader-text\">show1129<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[4],"tags":[],"class_list":["post-12461","post","type-post","status-publish","format-standard","hentry","category-programas"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/s8QBh9-show1129","jetpack-related-posts":[{"id":16749,"url":"https:\/\/encaso.volitivo.com\/site\/show5380\/","url_meta":{"origin":12461,"position":0},"title":"show5380","author":"ArchivoEncaso","date":"28\/10\/2022","format":false,"excerpt":"5380 Historias De Terror - ECDQEMSD viernes, 28 de octubre de 2022 Nos adentramos al clima de Halloween con narraciones donde el misterio, el miedo y el terror, se presentan como fantas\u00eda o hechos reales. ECDQEMSD podcast episodio 5380 Historias De Terror Conducen: El Pirata y El Sr. Lagartija https:\/\/canaltrans.com\u2026","rel":"","context":"En &quot;Programas&quot;","block_context":{"text":"Programas","link":"https:\/\/encaso.volitivo.com\/site\/category\/programas\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":16780,"url":"https:\/\/encaso.volitivo.com\/site\/show5411\/","url_meta":{"origin":12461,"position":1},"title":"show5411","author":"ArchivoEncaso","date":"12\/12\/2022","format":false,"excerpt":"5411 Fiesta En El Pueblo - ECDQEMSD lunes, 12 de diciembre de 2022 Entre chispas y fuegos artificiales el pueblo rend\u00eda homenaje a la Virgen de Guadalupe. Es el d\u00eda de la patrona de Am\u00e9rica aparecida a Juan Diego en el Cerro del Tepeyac. ECDQEMSD podcast episodio 5411 Fiesta En\u2026","rel":"","context":"En &quot;Programas&quot;","block_context":{"text":"Programas","link":"https:\/\/encaso.volitivo.com\/site\/category\/programas\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":16193,"url":"https:\/\/encaso.volitivo.com\/site\/show4951-3\/","url_meta":{"origin":12461,"position":2},"title":"show4951","author":"ArchivoEncaso","date":"08\/03\/2021","format":false,"excerpt":"4951 Ellas Pintadas - ECDQEMSD lunes, 8 de marzo de 2021 El pesado muro de metal, ese que proteg\u00eda el Palacio Nacional en Ciudad de M\u00e9xico, fue convertido en lienzo, en pared para dar el grito de las que ya no pueden. Expresiones en el D\u00eda Internacional de la Mujer\u2026","rel":"","context":"En &quot;Programas&quot;","block_context":{"text":"Programas","link":"https:\/\/encaso.volitivo.com\/site\/category\/programas\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":17044,"url":"https:\/\/encaso.volitivo.com\/site\/show5638\/","url_meta":{"origin":12461,"position":3},"title":"show5638","author":"ArchivoEncaso","date":"25\/10\/2023","format":false,"excerpt":"5638 Recetas Para Halloween - ECDQEMSD mi\u00e9rcoles, 25 de octubre de 2023 Las recetas m\u00e1s geniales para la mesa de la noche de Halloween o para entretenerse durante el d\u00eda esperando el cocktail recomendado para la Noche de Brujas. ECDQEMSD podcast El Cyber Talk Show - episodio 5638 Recetas Para\u2026","rel":"","context":"En &quot;Programas&quot;","block_context":{"text":"Programas","link":"https:\/\/encaso.volitivo.com\/site\/category\/programas\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":17395,"url":"https:\/\/encaso.volitivo.com\/site\/show5823\/","url_meta":{"origin":12461,"position":4},"title":"show5823","author":"ArchivoEncaso","date":"10\/07\/2024","format":false,"excerpt":"5823 Skinner y los Animales - ECDQEMSD mi\u00e9rcoles, 10 de julio de 2024 El psic\u00f3logo Burrhus Frederic Skinner, y sus experimentos con palomas, con las que investig\u00f3 como las consecuencias positivas y negativas moldean la conducta. A ese proceso le dio el nombre de condicionamiento ECDQEMSD podcast El Cyber Talk\u2026","rel":"","context":"En &quot;Programas&quot;","block_context":{"text":"Programas","link":"https:\/\/encaso.volitivo.com\/site\/category\/programas\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":14969,"url":"https:\/\/encaso.volitivo.com\/site\/2017-el-mundo-es-un-cabaret-mortal\/","url_meta":{"origin":12461,"position":5},"title":"2017 El Mundo Es Un Cabaret Mortal","author":"ArchivoEncaso","date":"16\/12\/2017","format":"video","excerpt":"Descripci\u00f3n de El Mundo Es Un Cabaret Mortal\u00a0- ECDQEMSD s\u00e1bado, 16 de diciembre de 2017 Canci\u00f3n de cierre de los Premios ECDQEMSD 2017 - Letra: El Pirata - Voz: El Sr. Lagartija - Grabado en La Mar\u00eda Tijuana - Dic. 2017 - El mundo es un cabaret mortal y est\u00e1s\u2026","rel":"","context":"En &quot;Especial&quot;","block_context":{"text":"Especial","link":"https:\/\/encaso.volitivo.com\/site\/category\/especial\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"_links":{"self":[{"href":"https:\/\/encaso.volitivo.com\/site\/wp-json\/wp\/v2\/posts\/12461","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/encaso.volitivo.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/encaso.volitivo.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/encaso.volitivo.com\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/encaso.volitivo.com\/site\/wp-json\/wp\/v2\/comments?post=12461"}],"version-history":[{"count":0,"href":"https:\/\/encaso.volitivo.com\/site\/wp-json\/wp\/v2\/posts\/12461\/revisions"}],"wp:attachment":[{"href":"https:\/\/encaso.volitivo.com\/site\/wp-json\/wp\/v2\/media?parent=12461"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/encaso.volitivo.com\/site\/wp-json\/wp\/v2\/categories?post=12461"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/encaso.volitivo.com\/site\/wp-json\/wp\/v2\/tags?post=12461"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}